{"id":12,"date":"2007-10-20T23:41:07","date_gmt":"2007-06-10T12:21:20","guid":{"rendered":""},"modified":"2009-01-19T22:38:54","modified_gmt":"2009-01-19T21:38:54","slug":"qui_est_neptune","status":"publish","type":"post","link":"https:\/\/www.cfardel.net\/blog\/qui_est_neptune","title":{"rendered":"Qui est  Neptune?"},"content":{"rendered":"<p>Je m&rsquo;appelle Neptune, je suis un chien-guide pour aveugle. J\u2019accompagne le webmaster de ce site dans ses d\u00e9placements quotidiens. Je viens de la Fondation<br \/>\n\u00c9cole Romande Chiens-guides \u00e0 Brenles (Suisse). Et voici ce qui s\u2019est pass\u00e9 pour moi, avant d\u2019\u00eatre confi\u00e9 \u00e0 mon ma\u00eetre :<\/p>\n<p>A l&rsquo;\u00e2ge de sept semaines, je suis parti pendant 15 mois dans une famille de parrainage. Cette famille m\u2019a appris \u00e0 bien me comporter en toutes circonstances<br \/>\nen me permettant de me familiariser avec le monde ext\u00e9rieur : on m\u2019a emmen\u00e9 dans des rues fr\u00e9quent\u00e9es, dans des magasins, dans les transports publiques,<br \/>\netc.<br \/>\nA 15 mois, je suis retourn\u00e9 dans l&rsquo;\u00e9cole pour commencer une formation de 8 \u00e0 9 mois avec un moniteur sp\u00e9cialis\u00e9. Il m\u2019a fait passer des tests pour v\u00e9rifier<br \/>\nsi je ne sursautais pas \u00e0 chaque bruit. Ensuite, j\u2019ai \u00e9t\u00e9 entra\u00een\u00e9 \u00e0 me tenir tranquille et concentrer au harnais.<\/p>\n<p>Maintenant, je suis capable de chercher des passages pi\u00e9tons, de rep\u00e9rer les changements de niveaux, d\u2019\u00e9viter les obstacles qui sont au niveau de mon ma\u00eetre<br \/>\net de sa t\u00eate.<br \/>\nFigurez-vous qu\u2019ils m\u2019ont fait pass\u00e9 un examen de fin de formation, et que je l\u2019ai r\u00e9ussi ! Cela signifie alors que je suis \u00ab bon pour le service \u00bb, qu\u2019on<br \/>\nva pouvoir me trouver un ma\u00eetre qui pourra appr\u00e9cier mon aide.<br \/>\nEt c\u2019est ainsi que, depuis le 10 avril 2006, je suis chez mon ma\u00eetre C\u00e9dric\u2026<\/p>\n<p><a href=\"http:\/\/galery.neptune06.net\">Cliquez ici <\/a>pour voir mes photos!<\/p>\n<p>Pour finir, permettez-moi de vous faire une demande : si vous voyez un chien-guide entrain de travailler, merci de ne pas le caresser.<\/p>\n<p>Neptune<\/p>\n<p>PS : merci \u00e0 mon ma\u00eetre pour m\u2019avoir aid\u00e9 \u00e0 r\u00e9diger cet article. Dans ma formation, on ne m\u2019a pas appris l\u2019orthographe !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je m&rsquo;appelle Neptune, je suis un chien-guide pour aveugle. J\u2019accompagne le webmaster de ce site dans ses d\u00e9placements quotidiens. Je viens de la Fondation \u00c9cole Romande Chiens-guides \u00e0 Brenles (Suisse). Et voici ce qui s\u2019est pass\u00e9 pour moi, avant d\u2019\u00eatre confi\u00e9 \u00e0 mon ma\u00eetre : A l&rsquo;\u00e2ge de sept semaines, je suis parti pendant 15 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,13],"tags":[],"class_list":["post-12","post","type-post","status-publish","format-standard","hentry","category-chien-guide","category-neptune"],"_links":{"self":[{"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/posts\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":1,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/posts\/12\/revisions"}],"predecessor-version":[{"id":115,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/posts\/12\/revisions\/115"}],"wp:attachment":[{"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/media?parent=12"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/categories?post=12"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/tags?post=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}