{"id":782,"date":"2013-06-21T15:31:46","date_gmt":"2013-06-21T13:31:46","guid":{"rendered":"http:\/\/www.cfardel.net\/blog\/?p=782"},"modified":"2013-06-21T15:31:46","modified_gmt":"2013-06-21T13:31:46","slug":"fonctionnement-de-base-dun-lecteur-decran","status":"publish","type":"post","link":"https:\/\/www.cfardel.net\/blog\/fonctionnement-de-base-dun-lecteur-decran","title":{"rendered":"Fonctionnement de base d&rsquo;un lecteur d&rsquo;\u00e9cran"},"content":{"rendered":"<p>Une vid\u00e9o montrant les principes de base du fonctionnement d&rsquo;un lecteur d&rsquo;\u00e9cran   (Synth\u00e8se vocale)  sous Windows Pour les personnes aveugles.<br \/>\n<a href=\"http:\/\/www.youtube.com\/watch?v=c_zknXJCPx0&#038;feature=youtu.be\" title=\"Vid\u00e9o fonctionnement de base d'un lecteur d'\u00e9cran\">Vid\u00e9o fonctionnement de base d&rsquo;un lecteur d&rsquo;\u00e9cran<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une vid\u00e9o montrant les principes de base du fonctionnement d&rsquo;un lecteur d&rsquo;\u00e9cran (Synth\u00e8se vocale) sous Windows Pour les personnes aveugles. Vid\u00e9o fonctionnement de base d&rsquo;un lecteur d&rsquo;\u00e9cran<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,27],"tags":[],"class_list":["post-782","post","type-post","status-publish","format-standard","hentry","category-accessibilite","category-lecteurs-decran"],"_links":{"self":[{"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/posts\/782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":1,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/posts\/782\/revisions"}],"predecessor-version":[{"id":783,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/posts\/782\/revisions\/783"}],"wp:attachment":[{"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/media?parent=782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/categories?post=782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfardel.net\/blog\/wp-json\/wp\/v2\/tags?post=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}